{"id":1946,"date":"2018-09-18T10:46:14","date_gmt":"2018-09-18T10:46:14","guid":{"rendered":"http:\/\/www.fcedu.uner.edu.ar\/biblioteca\/?p=1946"},"modified":"2022-05-06T15:59:51","modified_gmt":"2022-05-06T15:59:51","slug":"atencion-al-publico-la-toma-la-facultad","status":"publish","type":"post","link":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/","title":{"rendered":"Atenci\u00f3n al p\u00fablico durante la toma a la Facultad"},"content":{"rendered":"<h3><strong>El Departamento Biblioteca reitera que su horario de atenci\u00f3n al p\u00fablico es de 7:30 a 19:30 hs de lunes a viernes. <\/strong><\/h3>\n<h3><strong>Ante versiones que la \u00abBiblioteca est\u00e1 cerrada\u00bb, cabe aclarar que durante el per\u00edodo de \u00abtoma de la Facultad\u00bb, Biblioteca ha tenido y tiene sus puertas abiertas en el horario mencionado anteriormente, con atenci\u00f3n normal. Lo que ha estado cerrado es el edificio, su puerta de ingreso.<\/strong><\/h3>\n<h3><strong>En el d\u00eda de la fecha, qui\u00e9nes est\u00e1n realizando la \u00abtoma\u00bb, han decidido abrir las puertas del edificio, permitiendo el acceso a la biblioteca, en el horario de 10 a 12 y de 16 a 18 hs.<\/strong><\/h3>\n<p style=\"text-align: right\"><strong>18\/09\/2018<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento Biblioteca reitera que su horario de atenci\u00f3n al p\u00fablico es de 7:30 a 19:30 hs de lunes a viernes. Ante versiones que la \u00abBiblioteca est\u00e1 cerrada\u00bb, cabe aclarar que durante el per\u00edodo de \u00abtoma de la Facultad\u00bb, Biblioteca ha tenido y tiene sus puertas abiertas en el horario mencionado anteriormente, con atenci\u00f3n normal&#8230;. <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":14,"featured_media":1053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Atenci\u00f3n al p\u00fablico durante la toma a la Facultad - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atenci\u00f3n al p\u00fablico durante la toma a la Facultad - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;\" \/>\n<meta property=\"og:description\" content=\"El Departamento Biblioteca reitera que su horario de atenci\u00f3n al p\u00fablico es de 7:30 a 19:30 hs de lunes a viernes. Ante versiones que la \u00abBiblioteca est\u00e1 cerrada\u00bb, cabe aclarar que durante el per\u00edodo de \u00abtoma de la Facultad\u00bb, Biblioteca ha tenido y tiene sus puertas abiertas en el horario mencionado anteriormente, con atenci\u00f3n normal.... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/\" \/>\n<meta property=\"og:site_name\" content=\"Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-18T10:46:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-06T15:59:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2016\/09\/horario-cambio2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"570\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/\",\"url\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/\",\"name\":\"Atenci\u00f3n al p\u00fablico durante la toma a la Facultad - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;\",\"isPartOf\":{\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/#website\"},\"datePublished\":\"2018-09-18T10:46:14+00:00\",\"dateModified\":\"2022-05-06T15:59:51+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atenci\u00f3n al p\u00fablico durante la toma a la Facultad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/#website\",\"url\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/\",\"name\":\"Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;\",\"description\":\"Otro sitio m\u00e1s de Sitios de Portal FCEDU UNER\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atenci\u00f3n al p\u00fablico durante la toma a la Facultad - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/","og_locale":"es_ES","og_type":"article","og_title":"Atenci\u00f3n al p\u00fablico durante la toma a la Facultad - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","og_description":"El Departamento Biblioteca reitera que su horario de atenci\u00f3n al p\u00fablico es de 7:30 a 19:30 hs de lunes a viernes. Ante versiones que la \u00abBiblioteca est\u00e1 cerrada\u00bb, cabe aclarar que durante el per\u00edodo de \u00abtoma de la Facultad\u00bb, Biblioteca ha tenido y tiene sus puertas abiertas en el horario mencionado anteriormente, con atenci\u00f3n normal.... Read More","og_url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/","og_site_name":"Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","article_published_time":"2018-09-18T10:46:14+00:00","article_modified_time":"2022-05-06T15:59:51+00:00","og_image":[{"width":570,"height":390,"url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2016\/09\/horario-cambio2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/","url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/","name":"Atenci\u00f3n al p\u00fablico durante la toma a la Facultad - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","isPartOf":{"@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/#website"},"datePublished":"2018-09-18T10:46:14+00:00","dateModified":"2022-05-06T15:59:51+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/atencion-al-publico-la-toma-la-facultad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/"},{"@type":"ListItem","position":2,"name":"Atenci\u00f3n al p\u00fablico durante la toma a la Facultad"}]},{"@type":"WebSite","@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/#website","url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/","name":"Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","description":"Otro sitio m\u00e1s de Sitios de Portal FCEDU UNER","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"","url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/posts\/1946"}],"collection":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/comments?post=1946"}],"version-history":[{"count":5,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/posts\/1946\/revisions"}],"predecessor-version":[{"id":2466,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/posts\/1946\/revisions\/2466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/media\/1053"}],"wp:attachment":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/media?parent=1946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/categories?post=1946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/tags?post=1946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}