{"id":2824,"date":"2023-05-12T14:47:14","date_gmt":"2023-05-12T14:47:14","guid":{"rendered":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/?p=2824"},"modified":"2023-05-12T15:39:44","modified_gmt":"2023-05-12T15:39:44","slug":"presentacion-del-libro-sobre-la-historia-de-la-biblioteca","status":"publish","type":"post","link":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/","title":{"rendered":"Presentaci\u00f3n del libro sobre la historia de la Biblioteca"},"content":{"rendered":"<p>El jueves 11 de mayo de 2023 se present\u00f3 el libro sobre la historia de la biblioteca de la facultad de Ciencias de la Educaci\u00f3n de la UNER.<\/p>\n<p>El libro es el resultado de la investigaci\u00f3n que realizaron la Lic. Soledad Vitali, el Lic. \u00c1ngel Puebla y el Lic. Sim\u00f3n Volcoff entre los a\u00f1os 2018 y 2021. El minucioso trabajo llevado a cabo dio por resultado una tesis de producci\u00f3n evaluada con sobresaliente para alcanzar el t\u00edtulo de Licenciatura de Comunicaci\u00f3n Social. Posteriormente, la culmin\u00f3 en la confecci\u00f3n de un libro.<\/p>\n<p>En la obra se encuentran narrados 100 a\u00f1os de historia sobre el movimiento de los libros en los distintos momentos hist\u00f3ricos pol\u00edticos dentro de una de las bibliotecas m\u00e1s emblem\u00e1ticas de nuestra regi\u00f3n: la Biblioteca de la Facultad de Ciencias de la Educaci\u00f3n.<\/p>\n<p>En el libro se describe c\u00f3mo en cada \u00e9poca los libros fueron apareciendo y desapareciendo seg\u00fan las ideolog\u00edas e intereses hegem\u00f3nicos de cada momento pol\u00edtico-social.<\/p>\n<p>En la presentaci\u00f3n, adem\u00e1s de los autores, estuvieron acompa\u00f1ados por el Dr. Sebasti\u00e1n Rom\u00e1n, director de la tesis que dio origen a este proyecto y el Dr. Carlos Mar\u00edn, Vicedecano de la Facultad de Ciencias de la Educaci\u00f3n de la UNER, en car\u00e1cter de presentador y moderador.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"gdlr-shortcode-wrapper\"><div class=\"gdlr-gallery-item gdlr-item\" ><div class=\"gallery-column four columns\"><div class=\"gallery-item\"><a href=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2023\/05\/Libro-Historia-Biblioteca-0.jpg\" data-fancybox-group=\"gdlr-gal-1\" data-rel=\"fancybox\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2023\/05\/Libro-Historia-Biblioteca-0-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><span class=\"gallery-caption\"><\/span><\/div><\/div><div class=\"gallery-column four columns\"><div class=\"gallery-item\"><a href=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2023\/05\/Libro-Historia-Biblioteca-1.jpg\" data-fancybox-group=\"gdlr-gal-1\" data-rel=\"fancybox\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2023\/05\/Libro-Historia-Biblioteca-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><span class=\"gallery-caption\"><\/span><\/div><\/div><div class=\"gallery-column four columns\"><div class=\"gallery-item\"><a href=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2023\/05\/Libro-Historia-Biblioteca-3.jpg\" data-fancybox-group=\"gdlr-gal-1\" data-rel=\"fancybox\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2023\/05\/Libro-Historia-Biblioteca-3-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><span class=\"gallery-caption\"><\/span><\/div><\/div><div class=\"clear\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El jueves 11 de mayo de 2023 se present\u00f3 el libro sobre la historia de la biblioteca de la facultad de Ciencias de la Educaci\u00f3n de la UNER. El libro es el resultado de la investigaci\u00f3n que realizaron la Lic. Soledad Vitali, el Lic. \u00c1ngel Puebla y el Lic. Sim\u00f3n Volcoff entre los a\u00f1os 2018&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/\" class=\"excerpt-read-more\">Read More<i class=\"fa fa-caret-right icon-caret-right\"><\/i><\/a><\/p>\n","protected":false},"author":14,"featured_media":2830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presentaci\u00f3n del libro sobre la historia de la Biblioteca - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaci\u00f3n del libro sobre la historia de la Biblioteca - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;\" \/>\n<meta property=\"og:description\" content=\"El jueves 11 de mayo de 2023 se present\u00f3 el libro sobre la historia de la biblioteca de la facultad de Ciencias de la Educaci\u00f3n de la UNER. El libro es el resultado de la investigaci\u00f3n que realizaron la Lic. Soledad Vitali, el Lic. \u00c1ngel Puebla y el Lic. Sim\u00f3n Volcoff entre los a\u00f1os 2018... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/\" \/>\n<meta property=\"og:site_name\" content=\"Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-12T14:47:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-12T15:39:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2023\/05\/Tapa-Historia-de-la-biblioteca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"869\" \/>\n\t<meta property=\"og:image:height\" content=\"1241\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/\",\"url\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/\",\"name\":\"Presentaci\u00f3n del libro sobre la historia de la Biblioteca - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;\",\"isPartOf\":{\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/#website\"},\"datePublished\":\"2023-05-12T14:47:14+00:00\",\"dateModified\":\"2023-05-12T15:39:44+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentaci\u00f3n del libro sobre la historia de la Biblioteca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/#website\",\"url\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/\",\"name\":\"Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;\",\"description\":\"Otro sitio m\u00e1s de Sitios de Portal FCEDU UNER\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentaci\u00f3n del libro sobre la historia de la Biblioteca - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/","og_locale":"es_ES","og_type":"article","og_title":"Presentaci\u00f3n del libro sobre la historia de la Biblioteca - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","og_description":"El jueves 11 de mayo de 2023 se present\u00f3 el libro sobre la historia de la biblioteca de la facultad de Ciencias de la Educaci\u00f3n de la UNER. El libro es el resultado de la investigaci\u00f3n que realizaron la Lic. Soledad Vitali, el Lic. \u00c1ngel Puebla y el Lic. Sim\u00f3n Volcoff entre los a\u00f1os 2018... Read More","og_url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/","og_site_name":"Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","article_published_time":"2023-05-12T14:47:14+00:00","article_modified_time":"2023-05-12T15:39:44+00:00","og_image":[{"width":869,"height":1241,"url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-content\/uploads\/2023\/05\/Tapa-Historia-de-la-biblioteca.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/","url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/","name":"Presentaci\u00f3n del libro sobre la historia de la Biblioteca - Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","isPartOf":{"@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/#website"},"datePublished":"2023-05-12T14:47:14+00:00","dateModified":"2023-05-12T15:39:44+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/presentacion-del-libro-sobre-la-historia-de-la-biblioteca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/"},{"@type":"ListItem","position":2,"name":"Presentaci\u00f3n del libro sobre la historia de la Biblioteca"}]},{"@type":"WebSite","@id":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/#website","url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/","name":"Biblioteca &quot;Prof. N\u00e9lida Landreani&quot;","description":"Otro sitio m\u00e1s de Sitios de Portal FCEDU UNER","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"","url":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/posts\/2824"}],"collection":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/comments?post=2824"}],"version-history":[{"count":4,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/posts\/2824\/revisions"}],"predecessor-version":[{"id":2834,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/posts\/2824\/revisions\/2834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/media\/2830"}],"wp:attachment":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/media?parent=2824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/categories?post=2824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/biblioteca\/wp-json\/wp\/v2\/tags?post=2824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}