{"id":2797,"date":"2025-03-21T14:12:37","date_gmt":"2025-03-21T17:12:37","guid":{"rendered":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/?p=2797"},"modified":"2026-06-01T13:36:11","modified_gmt":"2026-06-01T16:36:11","slug":"del-prudente-saber-y-el-maximo-posible-de-sabor-21","status":"publish","type":"post","link":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/del-prudente-saber-y-el-maximo-posible-de-sabor-21\/","title":{"rendered":"del prudente Saber y el m\u00e1ximo posible de Sabor | 21"},"content":{"rendered":"<p><em>del prudente Saber y el m\u00e1ximo posible de Sabor<\/em>\u00a0es una publicaci\u00f3n arbitrada de la Facultad de Ciencias de la Educaci\u00f3n, Universidad Nacional de Entre R\u00edos.<br \/>\nLa revista puede ser le\u00edda y descargada de forma gratuita:<\/p>\n<p><a href=\"https:\/\/pcient.uner.edu.ar\/index.php\/dps\">https:\/\/pcient.uner.edu.ar\/index.php\/dps<\/a><\/p>\n<p>del prudente Saber y el m\u00e1ximo posible de Sabor<br \/>\nN.\u00b0 21 enero &#8211; junio, 2025<\/p>\n<p><strong>Director:<\/strong>\u00a0Sebasti\u00e1n Rom\u00e1n<\/p>\n<p><strong>A\u00f1o:<\/strong> 2025<\/p>\n<p><strong>e-ISSN:\u00a0\u00a0<\/strong>2618-4141<\/p>\n<p><strong>Sumario<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Editorial<\/strong><\/p>\n<p><a href=\"https:\/\/pcient.uner.edu.ar\/index.php\/dps\/article\/view\/2366\/2452\">Los objetos de lectura, entre lo pasional y lo amoroso |<\/a> Mario Sebasti\u00e1n Rom\u00e1n<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Art\u00edculos<\/strong><\/p>\n<p><a href=\"https:\/\/pcient.uner.edu.ar\/index.php\/dps\/article\/view\/2259\/2427\">Continuidades y cambios en la construcci\u00f3n de la agenda de ciencia y salud en la prensa argentina<\/a> | Mar\u00eda Cecilia Farr\u00e9<\/p>\n<p><a href=\"https:\/\/pcient.uner.edu.ar\/index.php\/dps\/article\/view\/2224\/2411\">Microexperiencias de literacidad ac\u00e1demica en el cambio escuela media-nivel superior<\/a> | Mar\u00eda Beatriz Taboada<\/p>\n<p><a href=\"https:\/\/pcient.uner.edu.ar\/index.php\/dps\/article\/view\/2080\/2338\">Noticia policial. Nuevas formas de expresi\u00f3n y producci\u00f3n en la prensa digital argentina<\/a> | Mariana Fern\u00e1ndez, Mar\u00eda del Rosario S\u00e1nchez<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rese\u00f1as\u00a0<\/strong><\/p>\n<p><a href=\"https:\/\/pcient.uner.edu.ar\/index.php\/dps\/article\/view\/2221\/2337\">Rese\u00f1a: Tiempos de reformas. Salud y educaci\u00f3n en la provincia de Santa Fe<\/a> | Adri\u00e1n Cammarota<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>del prudente Saber y el m\u00e1ximo posible de Sabor\u00a0es una publicaci\u00f3n arbitrada de la Facultad de Ciencias de la Educaci\u00f3n, Universidad Nacional de Entre R\u00edos. La revista puede&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[448,346,95,347,351],"tags":[],"_links":{"self":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/posts\/2797"}],"collection":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/comments?post=2797"}],"version-history":[{"count":3,"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/posts\/2797\/revisions"}],"predecessor-version":[{"id":2895,"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/posts\/2797\/revisions\/2895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/media\/2798"}],"wp:attachment":[{"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/media?parent=2797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/categories?post=2797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcedu.uner.edu.ar\/catalogo\/wp-json\/wp\/v2\/tags?post=2797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}